{"id":8531,"date":"2025-04-10T14:04:39","date_gmt":"2025-04-10T12:04:39","guid":{"rendered":"https:\/\/dev.freiwerk.de\/hawi\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/"},"modified":"2025-04-10T14:04:39","modified_gmt":"2025-04-10T12:04:39","slug":"capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres","status":"publish","type":"product","link":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/","title":{"rendered":"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres"},"content":{"rendered":"<p>Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres<\/p>\n","protected":false},"featured_media":4475,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[1074],"product_tag":[],"class_list":["post-8531","product","type-product","status-publish","has-post-thumbnail","product_cat-capuchons-de-protection-plats-decoratifs-et-de-couverture","first","instock","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres - HA-WI Kunststoffe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres - HA-WI Kunststoffe\" \/>\n<meta property=\"og:description\" content=\"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/\" \/>\n<meta property=\"og:site_name\" content=\"HA-WI Kunststoffe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ha-wi.com\/wp-content\/uploads\/2025\/02\/20450.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2128\" \/>\n\t<meta property=\"og:image:height\" content=\"1590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/\",\"url\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/\",\"name\":\"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres - HA-WI Kunststoffe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ha-wi.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20450.jpg\",\"datePublished\":\"2025-04-10T12:04:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ha-wi.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20450.jpg\",\"contentUrl\":\"https:\\\/\\\/ha-wi.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20450.jpg\",\"width\":2128,\"height\":1590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produkte\\\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/\",\"name\":\"HA-WI Kunststoffe: pr\u00e4zise Spritzgussteile aus Bad Laasphe\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/#organization\",\"name\":\"HA-WI Kunststoffe GmbH & Co. KG\",\"url\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ha-wi.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-hawi-kunststoffe.svg\",\"contentUrl\":\"https:\\\/\\\/ha-wi.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-hawi-kunststoffe.svg\",\"width\":1,\"height\":1,\"caption\":\"HA-WI Kunststoffe GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/ha-wi.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres - HA-WI Kunststoffe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/","og_locale":"fr_FR","og_type":"article","og_title":"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres - HA-WI Kunststoffe","og_description":"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres","og_url":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/","og_site_name":"HA-WI Kunststoffe","og_image":[{"width":2128,"height":1590,"url":"https:\/\/ha-wi.com\/wp-content\/uploads\/2025\/02\/20450.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/","url":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/","name":"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres - HA-WI Kunststoffe","isPartOf":{"@id":"https:\/\/ha-wi.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/#primaryimage"},"image":{"@id":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/#primaryimage"},"thumbnailUrl":"https:\/\/ha-wi.com\/wp-content\/uploads\/2025\/02\/20450.jpg","datePublished":"2025-04-10T12:04:39+00:00","breadcrumb":{"@id":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/#primaryimage","url":"https:\/\/ha-wi.com\/wp-content\/uploads\/2025\/02\/20450.jpg","contentUrl":"https:\/\/ha-wi.com\/wp-content\/uploads\/2025\/02\/20450.jpg","width":2128,"height":1590},{"@type":"BreadcrumbList","@id":"https:\/\/ha-wi.com\/fr\/produkte\/capuchon-a-tete-plate-pour-couvrir-les-vis-metalliques-avec-des-formes-de-tete-speciales-pour-les-vis-de-chevilles-pour-cadres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ha-wi.com\/fr\/page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/ha-wi.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Capuchon \u00e0 t\u00eate plate pour couvrir les vis m\u00e9talliques avec des formes de t\u00eate sp\u00e9ciales pour les vis de chevilles pour cadres"}]},{"@type":"WebSite","@id":"https:\/\/ha-wi.com\/fr\/#website","url":"https:\/\/ha-wi.com\/fr\/","name":"HA-WI Kunststoffe: pr\u00e4zise Spritzgussteile aus Bad Laasphe","description":"","publisher":{"@id":"https:\/\/ha-wi.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ha-wi.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ha-wi.com\/fr\/#organization","name":"HA-WI Kunststoffe GmbH & Co. KG","url":"https:\/\/ha-wi.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ha-wi.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ha-wi.com\/wp-content\/uploads\/2024\/08\/logo-hawi-kunststoffe.svg","contentUrl":"https:\/\/ha-wi.com\/wp-content\/uploads\/2024\/08\/logo-hawi-kunststoffe.svg","width":1,"height":1,"caption":"HA-WI Kunststoffe GmbH & Co. KG"},"image":{"@id":"https:\/\/ha-wi.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/product\/8531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/media\/4475"}],"wp:attachment":[{"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/media?parent=8531"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8531"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8531"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ha-wi.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}